{"id":308,"date":"2018-12-29T17:30:25","date_gmt":"2018-12-29T16:30:25","guid":{"rendered":"http:\/\/d7cgckuzbglox5ww.prev.site\/?page_id=308"},"modified":"2026-04-01T06:21:53","modified_gmt":"2026-04-01T04:21:53","slug":"kjoreplater","status":"publish","type":"page","link":"https:\/\/multiarena.no\/is\/keyrdarplotur\/","title":{"rendered":"KEYR\u00d0ARPL\u00d6TUR"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"308\" class=\"elementor elementor-308\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b06e797 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b06e797\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5a2c25b4\" data-id=\"5a2c25b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c0d5745 elementor-widget elementor-widget-heading\" data-id=\"4c0d5745\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Keyr\u00f0arpl\u00f6tur: Hin endanlega lausn til a\u00f0 vernda undirlag og draga \u00far kostna\u00f0i<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fa3305 elementor-widget elementor-widget-heading\" data-id=\"2fa3305\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">V\u00f6rur okkar \"Keyr\u00f0arpl\u00f6tur\"<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7013a96f elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"7013a96f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-49762a01 boks1\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/multiarena.no\/is\/fjolnota-golf\/signaroad\/\" data-column-clickable-blank=\"_self\" data-id=\"49762a01\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb37d86 min-ikonboks elementor-widget elementor-widget-icon-box\" data-id=\"bb37d86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<p class=\"product-title\"><span class=\"first-part\">Signa<\/span><span class=\"second-part\">road<\/span><\/p>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tKraftmiklar keyr\u00f0arpl\u00f6tur sem \u00feola \u00feung \u00f6kut\u00e6ki og mikla \u00e1lagningu.<br><br><br>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6aebaf00 boks2\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/multiarena.no\/is\/keyrdarplotur\/megadeck\/\" data-column-clickable-blank=\"_self\" data-id=\"6aebaf00\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ded683e elementor-widget elementor-widget-icon-box\" data-id=\"ded683e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<p class=\"product-title\"><span class=\"first-part\">Mega<\/span><span class=\"second-part\">Deck<\/span><\/p>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u00deolir allar \u00feyngstu \u00e1lagningar yfir erfi\u00f0asta landslagi\u00f0 \u00ed mestu krefjandi a\u00f0st\u00e6\u00f0um.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2760fe4 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"2760fe4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ac2604c boks2\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/multiarena.no\/is\/fjolnota-golf\/duradeck\/\" data-column-clickable-blank=\"_self\" data-id=\"ac2604c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa2b6ee elementor-widget elementor-widget-icon-box\" data-id=\"aa2b6ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<p class=\"product-title\"><span class=\"first-part\">Dura<\/span><span class=\"second-part\">Deck<\/span><\/p>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSterkt f\u00e6ranlegt vegkerfi fyrir a\u00f0gang og flutning. M\u00f3tast eftir landslaginu og \u00feolir \u00feung \u00f6kut\u00e6ki.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"make-column-clickable-elementor elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6155795 boks1\" style=\"cursor: pointer;\" data-column-clickable=\"https:\/\/multiarena.no\/is\/fjolnota-golf\/armordeck\/\" data-column-clickable-blank=\"_self\" data-id=\"6155795\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49d36db min-ikonboks elementor-widget elementor-widget-icon-box\" data-id=\"49d36db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<p class=\"product-title\"><span class=\"first-part\">Armor<\/span><span class=\"second-part\">Deck<\/span><\/p>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tKraftmiklar keyr\u00f0arpl\u00f6tur sem \u00feola \u00feung \u00f6kut\u00e6ki og mikla \u00e1lagningu.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0823980 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0823980\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-29a0a93 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"29a0a93\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9361f6e\" data-id=\"9361f6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb3288c elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"fb3288c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ma-comp-container\">\n    <table class=\"ma-comp-table\">\n        <thead>\n            <tr>\n                <th>Produkt<\/th>\n                <th>Type<\/th>\n                <th>Egenvekt<\/th>\n                <th>M\u00e5l (ca.)<\/th>\n                <th>Belastning<\/th>\n            <\/tr>\n        <\/thead>\n        <tbody>\n            <tr>\n                <td class=\"ma-comp-bold\">DuraDeck<\/td>\n                <td>Manuell h\u00e5ndtering<\/td>\n                <td>39 kg<\/td>\n                <td>2,44 x 1,22 m (8\u201d x 4\u201d)<\/td>\n                <td>80 tonn<\/td>\n            <\/tr>\n            <tr>\n                <td class=\"ma-comp-bold\">MegaDeck HD<\/td>\n                <td>Tung anleggsdrift<\/td>\n                <td>497 kg<\/td>\n                <td>4,27 x 2,29 m (14\u201d x 7,5\u201d)<\/td>\n                <td>42 kg\/cm\u00b2<\/td>\n            <\/tr>\n            <tr>\n                <td class=\"ma-comp-bold\">SignaRoad<\/td>\n                <td>T\u00edmabundinn vegur<\/td>\n                <td>225 kg<\/td>\n                <td>3,00 x 2,00 m (10\u201d x 6,5\u201d)<\/td>\n                <td>28 kg\/cm\u00b2<\/td>\n            <\/tr>\n            <tr>\n                <td class=\"ma-comp-bold\">ArmorDeck<\/td>\n                <td>Stadion\/Event<\/td>\n                <td>ca. 21 kg<\/td>\n                <td>1,07 x 1,07 m (3,5\u201d x 3,5\u201d)<\/td>\n                <td>42 kg\/cm\u00b2<\/td>\n            <\/tr>\n        <\/tbody>\n    <\/table>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa585ac elementor-hidden-desktop elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"aa585ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ma-comp-tablet-container\">\n    <table class=\"ma-comp-table-tablet\">\n        <thead>\n            <tr>\n                <th>Produkt<\/th>\n                <th>Type<\/th>\n                <th>Egenvekt<\/th>\n                <th>M\u00e5l (ca.)<\/th>\n                <th>Belastning<\/th>\n            <\/tr>\n        <\/thead>\n        <tbody>\n            <tr>\n                <td class=\"ma-comp-bold\">DuraDeck<\/td>\n                <td>Manuell h\u00e5ndtering<\/td>\n                <td>39 kg<\/td>\n                <td>2,44 x 1,22 m (8\u201d x 4\u201d)<\/td>\n                <td>80 tonn<\/td>\n            <\/tr>\n            <tr>\n                <td class=\"ma-comp-bold\">MegaDeck HD<\/td>\n                <td>Tung anleggsdrift<\/td>\n                <td>497 kg<\/td>\n                <td>4,27 x 2,29 m (14\u201d x 7,5\u201d)<\/td>\n                <td>42 kg\/cm\u00b2<\/td>\n            <\/tr>\n            <tr>\n                <td class=\"ma-comp-bold\">SignaRoad<\/td>\n                <td>T\u00edmabundinn vegur<\/td>\n                <td>225 kg<\/td>\n                <td>3,00 x 2,00 m (10\u201d x 6,5\u201d)<\/td>\n                <td>28 kg\/cm\u00b2<\/td>\n            <\/tr>\n            <tr>\n                <td class=\"ma-comp-bold\">ArmorDeck<\/td>\n                <td>Stadion\/Event<\/td>\n                <td>ca. 21 kg<\/td>\n                <td>1,07 x 1,07 m (3,5\u201d x 3,5\u201d)<\/td>\n                <td>42 kg\/cm\u00b2<\/td>\n            <\/tr>\n        <\/tbody>\n    <\/table>\n<\/div>\n\n<style>\n.ma-comp-table-tablet { width: 100%; border-collapse: collapse; font-size: 13px; border: 1px solid #ddd; }\n\/* M\u00f8rk gr\u00e5 bakgrunn og gyllen tekst i header *\/\n.ma-comp-table-tablet th { \n    background-color: #666361; \n    color: #f6b36d; \n    padding: 12px 8px; \n    text-align: left; \n    text-transform: normal;\n    font-size: 12px;\n}\n.ma-comp-table-tablet td { padding: 10px 8px; border-bottom: 1px solid #eee; border-right: 1px solid #eee; }\n.ma-comp-bold { font-weight: bold; color: #333; }\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-352e197 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-html\" data-id=\"352e197\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ma-comp-mobile-container\">\n    <div class=\"ma-mobile-card\">\n        <div class=\"ma-mobile-header\">DuraDeck<\/div>\n        <div class=\"ma-mobile-row\"><span>Type:<\/span> Manuell h\u00e5ndtering<\/div>\n        <div class=\"ma-mobile-row\"><span>Vekt\/M\u00e5l:<\/span> 39 kg \/ 2,44 x 1,22 m<\/div>\n        <div class=\"ma-mobile-row\"><span>Belastning:<\/span> 80 tonn<\/div>\n    <\/div>\n    \n    <div class=\"ma-mobile-card\">\n        <div class=\"ma-mobile-header\">MegaDeck HD<\/div>\n        <div class=\"ma-mobile-row\"><span>Type:<\/span> Tung anleggsdrift<\/div>\n        <div class=\"ma-mobile-row\"><span>Vekt\/M\u00e5l:<\/span> 497 kg \/ 4,27 x 2,29 m<\/div>\n        <div class=\"ma-mobile-row\"><span>Belastning:<\/span> 42 kg\/cm\u00b2<\/div>\n    <\/div>\n\n    <div class=\"ma-mobile-card\">\n        <div class=\"ma-mobile-header\">SignaRoad<\/div>\n        <div class=\"ma-mobile-row\"><span>Type:<\/span> T\u00edmabundinn vegur<\/div>\n        <div class=\"ma-mobile-row\"><span>Vekt\/M\u00e5l:<\/span> 225 kg \/ 3,00 x 2,00 m<\/div>\n        <div class=\"ma-mobile-row\"><span>Belastning:<\/span> 28 kg\/cm\u00b2<\/div>\n    <\/div>\n\n    <div class=\"ma-mobile-card\">\n        <div class=\"ma-mobile-header\">ArmorDeck<\/div>\n        <div class=\"ma-mobile-row\"><span>Type:<\/span> Stadion\/Event<\/div>\n        <div class=\"ma-mobile-row\"><span>Vekt\/M\u00e5l:<\/span> ca. 21 kg \/ 1,07 x 1,07 m<\/div>\n        <div class=\"ma-mobile-row\"><span>Belastning:<\/span> 42 kg\/cm\u00b2<\/div>\n    <\/div>\n<\/div>\n\n<style>\n.ma-mobile-card { border: 1px solid #ddd; border-radius: 4px; margin-bottom: 15px; background: #fff; overflow: hidden; }\n\/* M\u00f8rk gr\u00e5 bakgrunn og gyllen tekst i kort-header *\/\n.ma-mobile-header { \n    background: #666361; \n    color: #f6b36d; \n    padding: 10px 12px; \n    font-weight: 500; \n    text-transform: normal;\n    font-size: 14px;\n}\n.ma-mobile-row { padding: 8px 12px; border-bottom: 1px solid #eee; font-size: 13px; display: flex; justify-content: space-between; }\n.ma-mobile-row span { font-weight: bold; color: #666; }\n.ma-mobile-row:last-child { border-bottom: none; }\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9da8ce elementor-widget elementor-widget-heading\" data-id=\"c9da8ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Keyr\u00f0arpl\u00f6tur fr\u00e1 Multiarena - St\u00e6rsta v\u00f6ru\u00farvali\u00f0 \u00e1 marka\u00f0num.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69b6e9e elementor-widget elementor-widget-heading\" data-id=\"69b6e9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><h3 style=\"margin-top: -1px;margin-bottom: 0px\">Ledende leverand\u00f8r av kj\u00f8replater \/ kj\u00f8rematter med kraftfulle l\u00f8sninger for entrepren\u00f8rmarkedet<\/h3><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11a1c0d custom-list-spacing elementor-widget elementor-widget-text-editor\" data-id=\"11a1c0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Multiarena b\u00fd\u00f0ur upp \u00e1 \u00fdmsar ger\u00f0ir keyr\u00f0arplatna sem koma til m\u00f3ts vi\u00f0 vaxandi marka\u00f0 fyrir mismunandi tegundir verndarplatna me\u00f0 fj\u00f6lbreyttum lausnum!<\/p><p>Selskapets brede portef\u00f8lje av mobile gulv kan egne seg for \u00e5 lage midlertidige kj\u00f8resoner over s\u00e5rbart terreng. DuraDeck kj\u00f8replater\/kj\u00f8rematter, Signa Road terrengbeskyttelsesmatter og MegaDeck riggmatter utfyller entrepren\u00f8rmarkedet med kjempesterke plater til bruk for vei -og landskapsentrepren\u00f8rer.<\/p><p>Hvort sem \u00fea\u00f0 er fyrir einyrkja me\u00f0 minigr\u00f6fu, gar\u00f0yrkjumenn e\u00f0a fyrir \u00fej\u00f3\u00f0legt e\u00f0a al\u00fej\u00f3\u00f0legt fyrirt\u00e6ki me\u00f0 m\u00f6rg vi\u00f0skiptasvi\u00f0, b\u00fd\u00f0ur v\u00f6ru\u00farval okkar upp \u00e1 kj\u00f6rinn grunn fyrir hvert byggingarsv\u00e6\u00f0i!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc17b2c elementor-widget elementor-widget-button\" data-id=\"cc17b2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/multiarena.no\/is\/keyrdarplotur\/bruksomrader\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lestu meira um Notkunarsvi\u00f0<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e37a0f5 elementor-widget elementor-widget-heading\" data-id=\"e37a0f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00d3missandi au\u00f0lind fyrir st\u00f6\u00f0ugleika og vernd undirlagsins<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2643fc6 custom-list-spacing elementor-widget elementor-widget-text-editor\" data-id=\"2643fc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fr\u00e1 byggingu og verkfr\u00e6\u00f0i til vi\u00f0bur\u00f0a og h\u00e1t\u00ed\u00f0a, keyr\u00f0arpl\u00f6tur veita sterkan yfirbor\u00f0 fyrir \u00feungar v\u00e9lar eins og grafa, v\u00f6rub\u00edla, kerrur, ruslab\u00edla og lyftur. \u00c1 sama t\u00edma hj\u00e1lpa \u00fe\u00e6r til vi\u00f0 a\u00f0 vernda undirliggjandi yfirbor\u00f0 fr\u00e1 skemmdum og f\u00f6rum eftir farart\u00e6ki.<\/p><p>\u00deessar pl\u00f6tur geta veri\u00f0 s\u00e9rstaklega gagnlegar \u00e1 byggingar- e\u00f0a mannvirkjasv\u00e6\u00f0um \u00fear sem getur veri\u00f0 \u00f3jafnt landslag, m\u00fdrlendi e\u00f0a a\u00f0rar krefjandi a\u00f0st\u00e6\u00f0ur. Me\u00f0 \u00fev\u00ed a\u00f0 dreifa \u00feyngd \u00f6kut\u00e6kja og t\u00e6kja yfir st\u00e6rra sv\u00e6\u00f0i, vernda pl\u00f6turnar hellul\u00f6g\u00f0 g\u00f6ng, fl\u00edsal\u00f6g\u00f0 g\u00f6ng, ka\u00f0la, g\u00f3lf, malbik og a\u00f0rar yfirbor\u00f0. Me\u00f0 keyr\u00f0arpl\u00f6tum getur\u00f0u au\u00f0veldlega unni\u00f0 \u00ed g\u00f6r\u00f0um, gr\u00e6num sv\u00e6\u00f0um og \u00ed \u00f3snortinni n\u00e1tt\u00faru \u00e1n \u00feess a\u00f0 skilja eftir \u00feig f\u00f6r.<\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca81a47 elementor-widget elementor-widget-heading\" data-id=\"ca81a47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Reduktion \u00e1 kostna\u00f0i me\u00f0 keyr\u00f0arpl\u00f6tum<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbf4741 custom-list-spacing elementor-widget elementor-widget-text-editor\" data-id=\"bbf4741\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Me\u00f0 \u00fev\u00ed a\u00f0 fj\u00e1rfesta \u00ed keyr\u00f0arpl\u00f6tum okkar, mun \u00feetta lei\u00f0a til verulegs kostna\u00f0arsparna\u00f0ar hva\u00f0 var\u00f0ar hugsanlegar vi\u00f0ger\u00f0ir og vi\u00f0hald b\u00e6\u00f0i yfirbor\u00f0s og t\u00e6kjaparks. \u00de\u00e6r spara t\u00edma mi\u00f0a\u00f0 vi\u00f0 a\u00f0 leggja hef\u00f0bundna vegi. Skemmdir \u00e1 yfirbor\u00f0i vegna \u00feungra farart\u00e6kja e\u00f0a byggingav\u00e9la geta valdi\u00f0 verulegum kostna\u00f0i. \u00deessi kostna\u00f0ur getur tengst b\u00e6\u00f0i vi\u00f0ger\u00f0um \u00e1 landslagi og skiptum \u00e1 skemmdu efni eins og hellum, fl\u00edsum, malbiki og \u00e1l\u00edka.<\/p><p>St\u00e6rstu keyr\u00f0arpl\u00f6tukerfin hafa b\u00e6\u00f0i innbyggt \u00feyngdardreifingarkerfi og l\u00e6singarkerfi sem kemur \u00ed veg fyrir bilun \u00ed samskeytum. Me\u00f0 \u00fev\u00ed a\u00f0 leggja keyr\u00f0arpl\u00f6tur \u00e1 yfirbor\u00f0i\u00f0 dreifist \u00feyngd \u00feungra farart\u00e6kja e\u00f0a v\u00e9la jafnt yfir st\u00e6rra sv\u00e6\u00f0i. \u00deetta minnkar l\u00edkurnar \u00e1 \u00fev\u00ed a\u00f0 yfirbor\u00f0i\u00f0 ver\u00f0i fyrir skemmdum og for\u00f0ast \u00feannig kostna\u00f0 sem tengist vi\u00f0ger\u00f0um \u00e1 sl\u00edkum skemmdum. Pl\u00f6turnar veita \u00fev\u00ed eins konar tryggingu gegn \u00f3v\u00e6ntum kostna\u00f0i vi\u00f0 vi\u00f0ger\u00f0ir og vi\u00f0hald.<\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4542f12 elementor-widget elementor-widget-button\" data-id=\"4542f12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/multiarena.no\/is\/keyrdarplotur\/fordeler\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lestu meira um Kosti<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-481a9b1 custom-list-spacing elementor-widget elementor-widget-text-editor\" data-id=\"481a9b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Med Multiarena\u2019s l\u00f8sninger f\u00e5r du kj\u00f8replater i HDPE plast med vektb\u00e6rende kapasitet p\u00e5 opptil 600 psi (42,18 kg\/cm2). Disse platesystemene kan danne en midlertidig vei, en midlertidig parkeringsplass, en helikopterlandingsplass,\u00a0 en stabil arbeidsplattform for de tyngste kranene og anleggsmidlene med mer. Kan ogs\u00e5 etableres p\u00e5 b\u00e5de myr og sn\u00f8.<\/p><p>Produktene av HDPE med h\u00f8y tetthet, inneholder spesialiserte fyllstoffer som gj\u00f8r kj\u00f8replatene veldig sterke. UV og anti-statiske tilsetningsstoffer sikrer at disse komposittplatene t\u00e5ler tunge konstruksjoner og kj\u00f8ret\u00f8y og gis lang levetid. Multiarenas kj\u00f8replater er uv-bestandige, kan enkelt vaskes, lagres og sendes til neste anleggsplass. Platene kan brukes \u00e5r etter \u00e5r og gir en god avkastning p\u00e5 investeringen.<\/p><p>\u00cd krefjandi norr\u00e6nu landi og \u00ed erfi\u00f0um ve\u00f0rum \u00e6ttu \u00feessar sterku verndarpl\u00f6tur a\u00f0 vera \u00f3missandi hluti af \u00f6llum byggingarverkefnum. \u00de\u00e6r eru hanna\u00f0ar til a\u00f0 vernda vi\u00f0kv\u00e6ma j\u00f6r\u00f0 og yfirbor\u00f0 og tryggja a\u00f0 \u00feung farart\u00e6ki geti hreyfst \u00f6rugglega og skilvirkt. Ef \u00fe\u00fa ert a\u00f0 leita a\u00f0 traustum birgja fyrir keyr\u00f0arpl\u00f6tur til s\u00f6lu e\u00f0a leigu, hefur \u00fe\u00fa komi\u00f0 \u00e1 r\u00e9ttan sta\u00f0. Vi\u00f0 h\u00f6fum langa reynslu \u00ed greininni og bj\u00f3\u00f0um upp \u00e1 breitt \u00farval af keyr\u00f0arpl\u00f6tum fyrir allar \u00fearfir og \u00e1 samkeppnish\u00e6fu ver\u00f0i.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c846ae5 elementor-widget elementor-widget-heading\" data-id=\"c846ae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Myndasyrpa:<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a06e5dc elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"a06e5dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:12,&quot;sizes&quot;:[]},&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bildekarusell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 av 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/AD-Translucent-000811-VIII-01.webp\" alt=\"ArmorDeck er s\u00e9rhanna\u00f0 sem g\u00f3lf fyrir leikvanga og \u00ed\u00fer\u00f3ttah\u00fas\" \/><figcaption class=\"elementor-image-carousel-caption\">ArmorDeck er s\u00e9rhanna\u00f0 sem g\u00f3lf fyrir leikvanga og \u00ed\u00fer\u00f3ttah\u00fas<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 av 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/Busch-Stadium-5-ArmorDeck-02.webp\" alt=\"Armordeck - Fyrsti valkostur verktaka fyrir verndun leikvangs\" \/><figcaption class=\"elementor-image-carousel-caption\">Armordeck - Fyrsti valkostur verktaka fyrir verndun leikvangs<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 av 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/duradeck72-03.webp\" alt=\"Duradeck - Sterkar keyr\u00f0arpl\u00f6tur \u00far plasti\" \/><figcaption class=\"elementor-image-carousel-caption\">Duradeck - Sterkar keyr\u00f0arpl\u00f6tur \u00far plasti<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 av 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/duradeck75-04.webp\" alt=\"Duradeck - Keyr\u00f0arpl\u00f6tur til a\u00f0 vernda vi\u00f0kv\u00e6mt landslag\" \/><figcaption class=\"elementor-image-carousel-caption\">Duradeck - Keyr\u00f0arpl\u00f6tur til a\u00f0 vernda vi\u00f0kv\u00e6mt landslag<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 av 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/megadeck_myrmatter27-05.webp\" alt=\"Megadeck Keyr\u00f0arpl\u00f6tur nota\u00f0ar fyrir t\u00edmabundna vegi\" \/><figcaption class=\"elementor-image-carousel-caption\">Megadeck Keyr\u00f0arpl\u00f6tur nota\u00f0ar fyrir t\u00edmabundna vegi<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 av 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/megadeck_myrmatter56-06.webp\" alt=\"Megadeck myrmottur - Tilvali\u00f0 fyrir votlendissv\u00e6\u00f0i\" \/><figcaption class=\"elementor-image-carousel-caption\">Megadeck myrmottur - Tilvali\u00f0 fyrir votlendissv\u00e6\u00f0i<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 av 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/megadeck-square-07.webp\" alt=\"Megadeck motturnar eru au\u00f0veldar \u00ed uppsetningu og me\u00f0h\u00f6ndlun\" \/><figcaption class=\"elementor-image-carousel-caption\">Megadeck motturnar eru au\u00f0veldar \u00ed uppsetningu og me\u00f0h\u00f6ndlun<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 av 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/signaroad-install-2-1024x683-08.webp\" alt=\"Signaroad - Keyr\u00f0arpl\u00f6turnar eru au\u00f0veldar \u00ed uppsetningu\" \/><figcaption class=\"elementor-image-carousel-caption\">Signaroad - Keyr\u00f0arpl\u00f6turnar eru au\u00f0veldar \u00ed uppsetningu<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 av 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/signaroad-path-4-1024x683-09.webp\" alt=\"Signaroad keyr\u00f0arpl\u00f6tur fyrir st\u00f3r vi\u00f0bur\u00f0i\" \/><figcaption class=\"elementor-image-carousel-caption\">Signaroad keyr\u00f0arpl\u00f6tur fyrir st\u00f3r vi\u00f0bur\u00f0i<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 av 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/signaroad-staging-area-1024x683-10.webp\" alt=\"Signaroad - Keyr\u00f0arpl\u00f6tur \u00ed notkun \u00e1 vi\u00f0bur\u00f0asv\u00e6\u00f0i\" \/><figcaption class=\"elementor-image-carousel-caption\">Signaroad - Keyr\u00f0arpl\u00f6tur \u00ed notkun \u00e1 vi\u00f0bur\u00f0asv\u00e6\u00f0i<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 av 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/thumb_IMG_1379_1024-11.webp\" alt=\"Armordeck - Keyr\u00f0arpl\u00f6tur fyrir \u00f6ruggan a\u00f0gang\" \/><figcaption class=\"elementor-image-carousel-caption\">Armordeck - Keyr\u00f0arpl\u00f6tur fyrir \u00f6ruggan a\u00f0gang<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 av 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/truck_duradeck-12.webp\" alt=\"Duradeck - \u00deung \u00f6kut\u00e6ki engin hindrun\" \/><figcaption class=\"elementor-image-carousel-caption\">Duradeck - \u00deung \u00f6kut\u00e6ki engin hindrun<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0e466c1\" data-id=\"0e466c1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-723f631 elementor-widget elementor-widget-heading\" data-id=\"723f631\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Leigja e\u00f0a kaupa? \u00f3ska\u00f0u eftir tilbo\u00f0i!<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3f6db0 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d3f6db0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-address-book\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Yngve Svingen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+47%20%2093204350\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-phone\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+47 932 04 350<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:yngve@multiarena.no\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">yngve@multiarena.no<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06935f8 elementor-widget elementor-widget-spacer\" data-id=\"06935f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0bc1cf elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c0bc1cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-address-book\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Torgny Lars Bakken<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+47%2090020782\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+47 900 20 782<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:torgny@multiarena.no\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">torgny@multiarena.no<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2452178 greyme elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2452178\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-feeb21a\" data-id=\"feeb21a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f19cb2 elementor-widget elementor-widget-heading\" data-id=\"4f19cb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Notkunarsv\u00e6\u00f0i<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9a244e5 lightme elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a244e5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-68cd7b7\" data-id=\"68cd7b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32c76bb elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"32c76bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">T\u00edmabundinn vegur<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">B\u00edlast\u00e6\u00f0i til br\u00e1\u00f0abirg\u00f0a<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Byggingarsv\u00e6\u00f0i og vi\u00f0bur\u00f0asv\u00e6\u00f0i<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Graslendi, gar\u00f0ar, gar\u00f0sv\u00e6\u00f0i<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Malbik, hellul\u00f6g\u00f0 g\u00f6tustein, sandur, m\u00f6l<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Votlendissv\u00e6\u00f0i og strandsv\u00e6\u00f0i<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Au\u00f0lendi, \u00fej\u00f3\u00f0gar\u00f0ar og vi\u00f0kv\u00e6mt landslag<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sk\u00f3glendi, m\u00f3- og m\u00fdrarlandslag<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00cd\u00fer\u00f3ttaleikvangar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Br\u00e1\u00f0a- og bj\u00f6rgunara\u00f0ger\u00f0ir<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Herna\u00f0ara\u00f0ger\u00f0ir<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1478a0 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e1478a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/multiarena.no\/is\/keyrdarplotur\/bruksomrader\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lestu meira um Notkunarsvi\u00f0<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-af67b6e elementor-widget elementor-widget-spacer\" data-id=\"af67b6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcc03ef elementor-widget elementor-widget-spacer\" data-id=\"fcc03ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5e63d95 greyme elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e63d95\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5d41f6d\" data-id=\"5d41f6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf6064c elementor-widget elementor-widget-heading\" data-id=\"cf6064c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Kostir<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f538abe lightme elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f538abe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3c582a4\" data-id=\"3c582a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d56e7f1 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d56e7f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kemur \u00ed veg fyrir drullu a\u00f0st\u00e6\u00f0ur<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Verndar menn, v\u00e9lar og t\u00e6ki<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Verndun yfirbor\u00f0s\/vi\u00f0kv\u00e6mrar jar\u00f0ar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Veitir a\u00f0gengi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Au\u00f0velt a\u00f0 me\u00f0h\u00f6ndla\/flytja<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">L\u00f6ng l\u00edft\u00edmi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Au\u00f0velt a\u00f0 \u00fer\u00edfa<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Umhverfisv\u00e6nt<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Dregur \u00far kostna\u00f0i<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1db1810 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1db1810\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/multiarena.no\/is\/keyrdarplotur\/fordeler\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lestu meira um Kosti<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a1ee03b greyme elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1ee03b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bc0de52\" data-id=\"bc0de52\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3569804 elementor-widget elementor-widget-heading\" data-id=\"3569804\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Spurningar og sv\u00f6r<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e6cc49e lightme elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6cc49e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ebdd849\" data-id=\"ebdd849\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fde0df9 elementor-widget elementor-widget-accordion\" data-id=\"fde0df9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2661\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2661\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-square-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-caret-square-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\"><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2661\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2661\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2662\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2662\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-square-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-caret-square-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Hva\u00f0 getur Multiarena bo\u00f0i\u00f0 upp \u00e1 var\u00f0andi verndarpl\u00f6tur til a\u00f0 tryggja vi\u00f0kv\u00e6m sv\u00e6\u00f0i?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2662\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2662\"><p>Multiarena b\u00fd\u00f0ur upp \u00e1 fj\u00f6lbreytt \u00farval af keyr\u00f0arpl\u00f6tum og keyr\u00f0arm\u00f6ttum fyrir t\u00edmabundnar byggingar, b\u00edlast\u00e6\u00f0i og vi\u00f0bur\u00f0asv\u00e6\u00f0i. \u00cd v\u00f6ru\u00farvalinu eru DuraDeck Mattar, Signa Road Mattar, MegaDeck Rig Mattar og f\u00e6ranleg g\u00f3lf, \u00f6ll s\u00e9rh\u00f6nnu\u00f0 til a\u00f0 vernda vi\u00f0kv\u00e6m sv\u00e6\u00f0i eins og grasfl\u00f6tur, gar\u00f0a, gr\u00f3\u00f0ursetningar, votlendissv\u00e6\u00f0i og strandlengjur. \u00deessar slitsterku v\u00f6rur \u00feola \u00feunga umfer\u00f0 og erfi\u00f0ar ve\u00f0ura\u00f0st\u00e6\u00f0ur, og eru au\u00f0veldar \u00ed uppsetningu og ni\u00f0urrifi. S\u00e9rsni\u00f0nar lausnir eru \u00ed bo\u00f0i til a\u00f0 m\u00e6ta \u00fe\u00ednum s\u00e9rst\u00f6ku kr\u00f6fum, svo a\u00f0 vi\u00f0 getum fundi\u00f0 bestu a\u00f0l\u00f6gunina fyrir verkefni\u00f0 \u00feitt.<\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2663\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2663\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-square-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-caret-square-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Hva\u00f0a efni eru keyr\u00f0arpl\u00f6turnar okkar \u00far?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2663\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2663\"><p>Keyr\u00f0arpl\u00f6turnar eru \u00far HDPE me\u00f0 h\u00e1um e\u00f0lismassa og innihalda s\u00e9rh\u00e6f\u00f0 fylliefni til a\u00f0 veita styrk og endingarg\u00e6\u00f0i.<\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2664\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2664\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-square-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-caret-square-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Hva\u00f0 er h\u00e6gt a\u00f0 nota verndarpl\u00f6tur til?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2664\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2664\"><p>Verndarpl\u00f6tur m\u00e1 nota til a\u00f0 b\u00faa til t\u00edmabundna vegi, b\u00edlast\u00e6\u00f0i e\u00f0a vinnusv\u00e6\u00f0i fyrir \u00feyngstu krana og byggingab\u00fana\u00f0 til a\u00f0 for\u00f0ast skemmdir \u00e1 yfirbor\u00f0i.<\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2665\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2665\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-square-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-caret-square-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Hversu mikla \u00feyngdarb\u00e6randi getu hafa akpl\u00f6tur okkar \/ akmottur?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2665\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2665\"><p>Verndarpl\u00f6turnar fr\u00e1 Multiarena hafa \u00feyngdarb\u00e6randi getu allt a\u00f0 600 psi (42,18 kg\/cm\u00b2).<\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2666\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2666\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-caret-square-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-caret-square-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Eru akpl\u00f6turnar au\u00f0veldar \u00ed geymslu og flutningi til n\u00e6sta byggingarsta\u00f0ar?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2666\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2666\"><p>J\u00e1, \u00fe\u00e6r eru au\u00f0veldar \u00ed \u00fevotti, geymslu og flutningi til n\u00e6sta byggingarsta\u00f0ar.<\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><p><script src=\"moz-extension:\/\/d943f2e0-0150-453e-b7ae-4a1b51130df7\/js\/app.js\" type=\"text\/javascript\"><\/script><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e3871f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e3871f3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5f2393\" data-id=\"b5f2393\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-175febf elementor-widget elementor-widget-heading\" data-id=\"175febf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Myndb\u00f6nd<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-353a6366 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"353a6366\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14b5e401\" data-id=\"14b5e401\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e526bdc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e526bdc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9f254e3\" data-id=\"9f254e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af71ab3 elementor-widget elementor-widget-facebook-embed\" data-id=\"af71ab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"facebook-embed.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style=\"min-height: 1px\" class=\"elementor-facebook-widget fb-video\" data-href=\"https:\/\/web.facebook.com\/signaturesys\/videos\/941899180173319\/\" data-show-text=\"false\" data-allowfullscreen=\"false\" data-autoplay=\"false\" data-show-captions=\"false\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5d1fde9\" data-id=\"5d1fde9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca0ae3a elementor-widget elementor-widget-facebook-embed\" data-id=\"ca0ae3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"facebook-embed.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style=\"min-height: 1px\" class=\"elementor-facebook-widget fb-video\" data-href=\"https:\/\/web.facebook.com\/signaturesys\/videos\/2638016139786575\/\" data-show-text=\"false\" data-allowfullscreen=\"false\" data-autoplay=\"false\" data-show-captions=\"false\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b922885 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b922885\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8288cfa\" data-id=\"8288cfa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-311a990 elementor-widget elementor-widget-video\" data-id=\"311a990\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/eahsv2eqkRI&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5db7739\" data-id=\"5db7739\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d594263 elementor-widget elementor-widget-video\" data-id=\"d594263\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=kEbunoGuE2s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-27bbba81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27bbba81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3337224a\" data-id=\"3337224a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5d719aab\" data-id=\"5d719aab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39187735 elementor-widget elementor-widget-heading\" data-id=\"39187735\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NI\u00d0URHAL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bb257d gbutton elementor-widget elementor-widget-text-editor\" data-id=\"2bb257d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a style=\"color:#707070!important\" href=\"https:\/\/multiarena.no\/wp-content\/uploads\/2020\/09\/Market-Brochure_Construction.pdf\" target=\"_blank\" rel=\"noopener\">Market Bruchure Construction<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8703998\" data-id=\"8703998\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Kj\u00f8replater: Den ultimate l\u00f8sningen for \u00e5 beskytte underlaget og redusere kostnader V\u00e5re &laquo;Kj\u00f8replate&raquo; produkter Signaroad Kraftige kj\u00f8replater som t\u00e5ler tunge kj\u00f8ret\u00f8y og mye belastning MegaDeck St\u00f8tter de aller tyngste belastningene over det t\u00f8ffeste terrenget i de mest utfordrende omgivelsene. DuraDeck Sterk mobil vei for adkomst og transport. Formes etter terrenget og t\u00e5ler tunge kj\u00f8ret\u00f8y. ArmorDeck [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[7],"tags":[31,30,78,32],"class_list":["post-308","page","type-page","status-publish","hentry","category-kjoreplater","tag-kjorematter","tag-kjoreplater","tag-kjoreplater-i-plast","tag-mobil-vei"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kj\u00f8replater &amp; Anleggsmatter | Opptil 80 tonn | Leie &amp; Salg<\/title>\n<meta name=\"description\" content=\"Kj\u00f8replater for tung anleggsdrift. B\u00e6reevne opptil 80 tonn. 70.000 m\u00b2 p\u00e5 lager for rask levering og rigg. For vei, kran og anlegg. Be om prosjektpris.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/multiarena.no\/is\/kjoreplater\/\" \/>\n<meta property=\"og:locale\" content=\"is_IS\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kj\u00f8replater\" \/>\n<meta property=\"og:description\" content=\"Kj\u00f8replater for tung anleggsdrift. B\u00e6reevne opptil 80 tonn. 70.000 m\u00b2 p\u00e5 lager for rask levering og rigg. For vei, kran og anlegg. Be om prosjektpris.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/multiarena.no\/is\/kjoreplater\/\" \/>\n<meta property=\"og:site_name\" content=\"Multiarena AS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/multiarenaas\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T04:21:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/AD-Translucent-000811-VIII-01.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/multiarena.no\\\/kjoreplater\\\/\",\"url\":\"https:\\\/\\\/multiarena.no\\\/kjoreplater\\\/\",\"name\":\"Kj\u00f8replater & Anleggsmatter | Opptil 80 tonn | Leie & Salg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/multiarena.no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/multiarena.no\\\/kjoreplater\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/multiarena.no\\\/kjoreplater\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/multiarena.no\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AD-Translucent-000811-VIII-01.webp\",\"datePublished\":\"2018-12-29T16:30:25+00:00\",\"dateModified\":\"2026-04-01T04:21:53+00:00\",\"description\":\"Kj\u00f8replater for tung anleggsdrift. B\u00e6reevne opptil 80 tonn. 70.000 m\u00b2 p\u00e5 lager for rask levering og rigg. For vei, kran og anlegg. Be om prosjektpris.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/multiarena.no\\\/kjoreplater\\\/#breadcrumb\"},\"inLanguage\":\"is\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/multiarena.no\\\/kjoreplater\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"is\",\"@id\":\"https:\\\/\\\/multiarena.no\\\/kjoreplater\\\/#primaryimage\",\"url\":\"https:\\\/\\\/multiarena.no\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AD-Translucent-000811-VIII-01.webp\",\"contentUrl\":\"https:\\\/\\\/multiarena.no\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AD-Translucent-000811-VIII-01.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/multiarena.no\\\/kjoreplater\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/multiarena.no\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kj\u00f8replater\",\"item\":\"http:\\\/\\\/multiarena.no\\\/en\\\/category\\\/kjoreplater\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kj\u00f8replater\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/multiarena.no\\\/#website\",\"url\":\"https:\\\/\\\/multiarena.no\\\/\",\"name\":\"Multiarena AS\",\"description\":\"Mobile gulv for enhver anledning!\",\"publisher\":{\"@id\":\"https:\\\/\\\/multiarena.no\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/multiarena.no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"is\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/multiarena.no\\\/#organization\",\"name\":\"Multiarena AS\",\"url\":\"https:\\\/\\\/multiarena.no\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"is\",\"@id\":\"https:\\\/\\\/multiarena.no\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/multiarena.no\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Multiarena-logo_medium.png\",\"contentUrl\":\"https:\\\/\\\/multiarena.no\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Multiarena-logo_medium.png\",\"width\":604,\"height\":120,\"caption\":\"Multiarena AS\"},\"image\":{\"@id\":\"https:\\\/\\\/multiarena.no\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/multiarenaas\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kj\u00f8replater & Anleggsmatter | Opptil 80 tonn | Leie & Salg","description":"Kj\u00f8replater for tung anleggsdrift. B\u00e6reevne opptil 80 tonn. 70.000 m\u00b2 p\u00e5 lager for rask levering og rigg. For vei, kran og anlegg. Be om prosjektpris.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/multiarena.no\/is\/kjoreplater\/","og_locale":"is_IS","og_type":"article","og_title":"Kj\u00f8replater","og_description":"Kj\u00f8replater for tung anleggsdrift. B\u00e6reevne opptil 80 tonn. 70.000 m\u00b2 p\u00e5 lager for rask levering og rigg. For vei, kran og anlegg. Be om prosjektpris.","og_url":"https:\/\/multiarena.no\/is\/kjoreplater\/","og_site_name":"Multiarena AS","article_publisher":"https:\/\/www.facebook.com\/multiarenaas","article_modified_time":"2026-04-01T04:21:53+00:00","og_image":[{"url":"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/AD-Translucent-000811-VIII-01.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/multiarena.no\/kjoreplater\/","url":"https:\/\/multiarena.no\/kjoreplater\/","name":"Kj\u00f8replater & Anleggsmatter | Opptil 80 tonn | Leie & Salg","isPartOf":{"@id":"https:\/\/multiarena.no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/multiarena.no\/kjoreplater\/#primaryimage"},"image":{"@id":"https:\/\/multiarena.no\/kjoreplater\/#primaryimage"},"thumbnailUrl":"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/AD-Translucent-000811-VIII-01.webp","datePublished":"2018-12-29T16:30:25+00:00","dateModified":"2026-04-01T04:21:53+00:00","description":"Kj\u00f8replater for tung anleggsdrift. B\u00e6reevne opptil 80 tonn. 70.000 m\u00b2 p\u00e5 lager for rask levering og rigg. For vei, kran og anlegg. Be om prosjektpris.","breadcrumb":{"@id":"https:\/\/multiarena.no\/kjoreplater\/#breadcrumb"},"inLanguage":"is","potentialAction":[{"@type":"ReadAction","target":["https:\/\/multiarena.no\/kjoreplater\/"]}]},{"@type":"ImageObject","inLanguage":"is","@id":"https:\/\/multiarena.no\/kjoreplater\/#primaryimage","url":"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/AD-Translucent-000811-VIII-01.webp","contentUrl":"https:\/\/multiarena.no\/wp-content\/uploads\/2024\/05\/AD-Translucent-000811-VIII-01.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/multiarena.no\/kjoreplater\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/multiarena.no\/"},{"@type":"ListItem","position":2,"name":"Kj\u00f8replater","item":"http:\/\/multiarena.no\/en\/category\/kjoreplater\/"},{"@type":"ListItem","position":3,"name":"Kj\u00f8replater"}]},{"@type":"WebSite","@id":"https:\/\/multiarena.no\/#website","url":"https:\/\/multiarena.no\/","name":"Multiarena AS","description":"Mobile gulv for enhver anledning!","publisher":{"@id":"https:\/\/multiarena.no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/multiarena.no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"is"},{"@type":"Organization","@id":"https:\/\/multiarena.no\/#organization","name":"Multiarena AS","url":"https:\/\/multiarena.no\/","logo":{"@type":"ImageObject","inLanguage":"is","@id":"https:\/\/multiarena.no\/#\/schema\/logo\/image\/","url":"https:\/\/multiarena.no\/wp-content\/uploads\/2018\/12\/Multiarena-logo_medium.png","contentUrl":"https:\/\/multiarena.no\/wp-content\/uploads\/2018\/12\/Multiarena-logo_medium.png","width":604,"height":120,"caption":"Multiarena AS"},"image":{"@id":"https:\/\/multiarena.no\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/multiarenaas"]}]}},"_links":{"self":[{"href":"https:\/\/multiarena.no\/is\/wp-json\/wp\/v2\/pages\/308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/multiarena.no\/is\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/multiarena.no\/is\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/multiarena.no\/is\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/multiarena.no\/is\/wp-json\/wp\/v2\/comments?post=308"}],"version-history":[{"count":58,"href":"https:\/\/multiarena.no\/is\/wp-json\/wp\/v2\/pages\/308\/revisions"}],"predecessor-version":[{"id":8534,"href":"https:\/\/multiarena.no\/is\/wp-json\/wp\/v2\/pages\/308\/revisions\/8534"}],"wp:attachment":[{"href":"https:\/\/multiarena.no\/is\/wp-json\/wp\/v2\/media?parent=308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/multiarena.no\/is\/wp-json\/wp\/v2\/categories?post=308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiarena.no\/is\/wp-json\/wp\/v2\/tags?post=308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}