{"id":278,"date":"2018-12-29T17:25:14","date_gmt":"2018-12-29T16:25:14","guid":{"rendered":"http:\/\/d7cgckuzbglox5ww.prev.site\/?page_id=278"},"modified":"2026-03-30T10:20:56","modified_gmt":"2026-03-30T08:20:56","slug":"telttojen-ja-salien-lattiat","status":"publish","type":"page","link":"https:\/\/multiarena.no\/fi\/telt-og-eventgulv\/","title":{"rendered":"Lattiat telttoihin &amp; halleihin"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"278\" class=\"elementor elementor-278\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75f27ecc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75f27ecc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5ea4aebf\" data-id=\"5ea4aebf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d3c3ab3 elementor-widget elementor-widget-heading\" data-id=\"7d3c3ab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lattia telttoihin<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25015f58 elementor-widget elementor-widget-text-editor\" data-id=\"25015f58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Suuren tapahtuman valmistelu alkaa usein hyv\u00e4ll\u00e4 pohjalla. Multiarena tarjoaa useita erityyppisi\u00e4 ja ensiluokkaisia \u200b\u200bteltta- ja tapahtumalattioita, jotka on suunniteltu vastaamaan kaikenkokoisia tarpeita. Ne tarjoavat samalla asianmukaisen suojan nurmikoille ja muille herkille pinnoille. Multiarenan teltta- ja tapahtumalattiat auttavat luomaan monipuolisen tapahtuman, ja ne ovat t\u00e4ydellinen ja kustannustehokas vaihtoehto kalliille puulattioille ja terasseille. Ne takaavat nopea kokoonpano- ja purkuajan, helpon puhdistuksen ja uudelleenk\u00e4ytt\u00f6mahdollisuuden vuosiksi eteenp\u00e4in. Multiarenan teltta- ja tapahtumalattia tarjoaa merkitt\u00e4v\u00e4n tuoton sijoitukselle.<\/p><p>Multiarenan valikoima soveltuu erinomaisesti sek\u00e4 messu- ett\u00e4 teollisuuslattiaksi, ja sit\u00e4 k\u00e4ytt\u00e4v\u00e4t sek\u00e4 tapahtumateollisuus ett\u00e4 rakennusala, puolustuvoimat ja pelastuslaitos.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07b4c4a elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"07b4c4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ma-comp-container\">\n    <table class=\"ma-comp-table\">\n        <thead>\n            <tr>\n                <th>Tuote<\/th>\n                <th>Tyyppi<\/th>\n                <th>Kantavuus<\/th>\n                <th>K\u00e4ytt\u00f6kohde<\/th>\n            <\/tr>\n        <\/thead>\n        <tbody>\n            <tr>\n                <td class=\"ma-comp-bold\">EventDeck<\/td>\n                <td>Moduulilattia<\/td>\n                <td>3,9 kg\/cm\u00b2<\/td>\n                <td>Teltat, nurmikon suojaus, kulkuv\u00e4yl\u00e4t<\/td>\n            <\/tr>\n            <tr>\n                <td class=\"ma-comp-bold\">UltraDeck<\/td>\n                <td>Moduulilattia<\/td>\n                <td>14,6 kg\/cm\u00b2<\/td>\n                <td>Messut, konsertit, kevyt ajo<\/td>\n            <\/tr>\n            <tr>\n                <td class=\"ma-comp-bold\">ArmorDeck<\/td>\n                <td>Heavy Duty -moduuli<\/td>\n                <td>42 kg\/cm\u00b2<\/td>\n                <td>Lavarakenteet, stadionkonsertit<\/td>\n            <\/tr>            \n            <tr>\n                <td class=\"ma-comp-bold\">HexaDeck<\/td>\n                <td>Kuusikulmainen moduuli<\/td>\n                <td>14,6 kg\/cm\u00b2<\/td>\n                <td>Kulkuv\u00e4yl\u00e4t, VIP-alueet<\/td>\n            <\/tr>\n        <\/tbody>\n    <\/table>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3cb8329 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cb8329\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-214d82d\" data-id=\"214d82d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-265f491a elementor-widget elementor-widget-heading\" data-id=\"265f491a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tuotteet<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c8d837f elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8d837f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eba2f27\" data-id=\"eba2f27\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c9e984 elementor-widget elementor-widget-image\" data-id=\"4c9e984\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square.webp\" class=\"attachment-large size-large wp-image-462\" alt=\"\" srcset=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square.webp 600w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square-150x150.webp 150w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square-300x300.webp 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ec0dd8 elementor-widget elementor-widget-heading\" data-id=\"5ec0dd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eventdeck<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3c1499 elementor-widget elementor-widget-text-editor\" data-id=\"e3c1499\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Teltgulv for personell<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b15645f\" data-id=\"b15645f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0de835 elementor-widget elementor-widget-image\" data-id=\"b0de835\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"553\" height=\"279\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/UltraDeck-square-e1585915483351.webp\" class=\"attachment-large size-large wp-image-468\" alt=\"\" srcset=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/UltraDeck-square-e1585915483351.webp 553w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/UltraDeck-square-e1585915483351-350x177.webp 350w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd9215f elementor-widget elementor-widget-heading\" data-id=\"fd9215f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ultradeck<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a295590 elementor-widget elementor-widget-text-editor\" data-id=\"a295590\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Teltgulv for personell og lettere transport<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-61e96ed elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61e96ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7e60693\" data-id=\"7e60693\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70ad797 elementor-widget elementor-widget-image\" data-id=\"70ad797\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/ArmorDeck-square.webp\" class=\"attachment-large size-large wp-image-456\" alt=\"\" srcset=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/ArmorDeck-square.webp 600w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/ArmorDeck-square-150x150.webp 150w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/ArmorDeck-square-300x300.webp 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17c2fee elementor-widget elementor-widget-heading\" data-id=\"17c2fee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Armordeck<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cefd4a elementor-widget elementor-widget-text-editor\" data-id=\"6cefd4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Teltgulv for personell og tyngre transport<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-de55c6b\" data-id=\"de55c6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-760ffba elementor-widget elementor-widget-image\" data-id=\"760ffba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/hexadeck-square.webp\" class=\"attachment-large size-large wp-image-808\" alt=\"\" srcset=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/hexadeck-square.webp 600w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/hexadeck-square-150x150.webp 150w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/hexadeck-square-300x300.webp 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5066d67 elementor-widget elementor-widget-heading\" data-id=\"5066d67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hexadeck<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12bf653 elementor-widget elementor-widget-text-editor\" data-id=\"12bf653\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Teltgulv for personell og tyngre transport.<br \/>Spesielt velegnet i runde telt<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-56cd1987\" data-id=\"56cd1987\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b8a9d03 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b8a9d03\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3ab42d8c\" data-id=\"3ab42d8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71b45b50 elementor-widget elementor-widget-heading\" data-id=\"71b45b50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Multiarena - fordeler<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3334d538 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3334d538\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-16ebf465\" data-id=\"16ebf465\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ae37de4 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6ae37de4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-check\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rask installasjon, lave arbeidskostnader<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-check\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gjenbruk i mange \u00e5r, betydelig avkastning p\u00e5 investeringen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-check\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lite vedlikehold, lett \u00e5 rengj\u00f8re<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-check\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Flatt, fast, komfortabelt gulv<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-check\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">H\u00e5ndterer tungt utstyr og mye publikum, beskytter underflater<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7aa4d81b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7aa4d81b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c2cb27b\" data-id=\"2c2cb27b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e7d43ea elementor-widget elementor-widget-menu-anchor\" data-id=\"6e7d43ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"products\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a8f3f17 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a8f3f17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-46d8963a\" data-id=\"46d8963a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48b63a87 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"48b63a87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"\/fi\/siirrettavat-lattiat\/eventdeck\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square-300x300.webp\" class=\"attachment-medium size-medium wp-image-462\" alt=\"\" srcset=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square-300x300.webp 300w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square-150x150.webp 150w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square.webp 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"\/fi\/siirrettavat-lattiat\/eventdeck\/\">EventDeck<\/a><\/h3><p class=\"elementor-image-box-description\">Teltgulv for personell<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-24c8647c\" data-id=\"24c8647c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ee5918e elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2ee5918e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"\/fi\/siirrettavat-lattiat\/ultradeck\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"177\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/UltraDeck-square-e1585915483351-350x177.webp\" class=\"attachment-medium size-medium wp-image-468\" alt=\"\" srcset=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/UltraDeck-square-e1585915483351-350x177.webp 350w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/UltraDeck-square-e1585915483351.webp 553w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"\/fi\/siirrettavat-lattiat\/ultradeck\/\">UltraDeck<\/a><\/h3><p class=\"elementor-image-box-description\">Teltgulv for personell og lettere transport<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f6971c5\" data-id=\"f6971c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d09831b elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1d09831b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"\/fi\/siirrettavat-lattiat\/armordeck\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/ArmorDeck-square-300x300.webp\" class=\"attachment-medium size-medium wp-image-456\" alt=\"\" srcset=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/ArmorDeck-square-300x300.webp 300w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/ArmorDeck-square-150x150.webp 150w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/ArmorDeck-square.webp 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"\/fi\/siirrettavat-lattiat\/armordeck\/\">ArmorDeck<\/a><\/h3><p class=\"elementor-image-box-description\">Teltgulv for personell og tyngre transport<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6aefb1d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6aefb1d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-391ef9a5\" data-id=\"391ef9a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2743d380 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2743d380\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"\/fi\/telttojen-ja-salien-lattiat\/hexadeck\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/hexadeck-square-300x300.webp\" class=\"attachment-medium size-medium wp-image-808\" alt=\"\" srcset=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/hexadeck-square-300x300.webp 300w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/hexadeck-square-150x150.webp 150w, https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/hexadeck-square.webp 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"\/fi\/telttojen-ja-salien-lattiat\/hexadeck\/\">HexaDeck<\/a><\/h3><p class=\"elementor-image-box-description\">Teltgulv for personell og tyngre transport. Spesielt velegnet i runde telt. <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7b03f5b5\" data-id=\"7b03f5b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-743f1164\" data-id=\"743f1164\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12b0493 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12b0493\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17d6243\" data-id=\"17d6243\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9caaad3 elementor-widget elementor-widget-heading\" data-id=\"9caaad3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Yhteyshenkil\u00f6t<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-514f4c6f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"514f4c6f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-13ec5630\" data-id=\"13ec5630\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fc6268d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6fc6268d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-address-book\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Torgny Lars Bakken<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+47%2090020782\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-phone\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+47 900 20 782<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:torgny@multiarena.no\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">torgny@multiarena.no<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6220f68\" data-id=\"6220f68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14134838 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"14134838\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-address-book\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Andre Holthe<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+47%20%2092%2088%2068%2018\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-phone\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+47 928 86 818<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:andre@multiarena.no\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">andre@multiarena.no<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Gulv til telt &#8211; Teltgulv Forberedelsene til det neste store arrangementet starter ofte med et godt grunnlag. Multiarena tilbyr flere typer f\u00f8rsteklasses telt- og eventgulv som er konstruert for \u00e5 dekke behovene for alle gulvst\u00f8rrelser, store eller sm\u00e5, samtidig som de gir en skikkelig beskyttelse til plener og andre typer sensitive underlag. Multiarenas telt- og [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[16],"tags":[39,36,80,40,79],"class_list":["post-278","page","type-page","status-publish","hentry","category-telt-og-eventgulv","tag-beskyttelse-av-naturgress","tag-beskyttelse-av-sarbart-underlag","tag-eventgulv","tag-kraftig-teltgulv","tag-teltgulv"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Telt- og Eventgulv | Messer &amp; Festivaler | 3-7 \u00c5rs Garanti<\/title>\n<meta name=\"description\" content=\"Mobile teltgulv for messer og event. T\u00e5ler alt fra publikumsmasser til lett transport. Fra verkt\u00f8yfrie gangveier til 80 tonns plater. Sjekk utvalget.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/multiarena.no\/fi\/telttojen-ja-salien-lattiat\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Telt- og Eventgulv\" \/>\n<meta property=\"og:description\" content=\"Mobile teltgulv for messer og event. T\u00e5ler alt fra publikumsmasser til lett transport. Fra verkt\u00f8yfrie gangveier til 80 tonns plater. Sjekk utvalget.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/multiarena.no\/fi\/telttojen-ja-salien-lattiat\/\" \/>\n<meta property=\"og:site_name\" content=\"Multiarena AS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/multiarenaas\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T08:20:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Arvioitu lukuaika\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuuttia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/multiarena.no\\\/telt-og-eventgulv\\\/\",\"url\":\"https:\\\/\\\/multiarena.no\\\/telt-og-eventgulv\\\/\",\"name\":\"Telt- og Eventgulv | Messer & Festivaler | 3-7 \u00c5rs Garanti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/multiarena.no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/multiarena.no\\\/telt-og-eventgulv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/multiarena.no\\\/telt-og-eventgulv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/multiarena.no\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/EventDeck-square.webp\",\"datePublished\":\"2018-12-29T16:25:14+00:00\",\"dateModified\":\"2026-03-30T08:20:56+00:00\",\"description\":\"Mobile teltgulv for messer og event. T\u00e5ler alt fra publikumsmasser til lett transport. Fra verkt\u00f8yfrie gangveier til 80 tonns plater. Sjekk utvalget.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/multiarena.no\\\/telt-og-eventgulv\\\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/multiarena.no\\\/telt-og-eventgulv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/multiarena.no\\\/telt-og-eventgulv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/multiarena.no\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/EventDeck-square.webp\",\"contentUrl\":\"https:\\\/\\\/multiarena.no\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/EventDeck-square.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/multiarena.no\\\/telt-og-eventgulv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/multiarena.no\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Telt- og eventgulv\",\"item\":\"http:\\\/\\\/multiarena.no\\\/en\\\/category\\\/telt-og-eventgulv\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Telt- og Eventgulv\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/multiarena.no\\\/#website\",\"url\":\"https:\\\/\\\/multiarena.no\\\/\",\"name\":\"Multiarena AS\",\"description\":\"Mobile gulv for enhver anledning!\",\"publisher\":{\"@id\":\"https:\\\/\\\/multiarena.no\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/multiarena.no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/multiarena.no\\\/#organization\",\"name\":\"Multiarena AS\",\"url\":\"https:\\\/\\\/multiarena.no\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/multiarena.no\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/multiarena.no\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Multiarena-logo_medium.png\",\"contentUrl\":\"https:\\\/\\\/multiarena.no\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Multiarena-logo_medium.png\",\"width\":604,\"height\":120,\"caption\":\"Multiarena AS\"},\"image\":{\"@id\":\"https:\\\/\\\/multiarena.no\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/multiarenaas\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Teltta- ja tapahtumalattiat | Messut &amp; Festivaalit | 3\u20137 v takuu","description":"Siirrett\u00e4v\u00e4t telttalattiat messuille ja tapahtumiin. Kest\u00e4\u00e4 yleis\u00f6massat ja kevyen kuljetuksen. Valikoima ulottuu k\u00e4velyteist\u00e4 80 tonnin levyihin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/multiarena.no\/fi\/telttojen-ja-salien-lattiat\/","og_locale":"fi_FI","og_type":"article","og_title":"Telt- og Eventgulv","og_description":"Mobile teltgulv for messer og event. T\u00e5ler alt fra publikumsmasser til lett transport. Fra verkt\u00f8yfrie gangveier til 80 tonns plater. Sjekk utvalget.","og_url":"https:\/\/multiarena.no\/fi\/telttojen-ja-salien-lattiat\/","og_site_name":"Multiarena AS","article_publisher":"https:\/\/www.facebook.com\/multiarenaas","article_modified_time":"2026-03-30T08:20:56+00:00","og_image":[{"url":"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Arvioitu lukuaika":"4 minuuttia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/multiarena.no\/telt-og-eventgulv\/","url":"https:\/\/multiarena.no\/telt-og-eventgulv\/","name":"Teltta- ja tapahtumalattiat | Messut &amp; Festivaalit | 3\u20137 v takuu","isPartOf":{"@id":"https:\/\/multiarena.no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/multiarena.no\/telt-og-eventgulv\/#primaryimage"},"image":{"@id":"https:\/\/multiarena.no\/telt-og-eventgulv\/#primaryimage"},"thumbnailUrl":"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square.webp","datePublished":"2018-12-29T16:25:14+00:00","dateModified":"2026-03-30T08:20:56+00:00","description":"Siirrett\u00e4v\u00e4t telttalattiat messuille ja tapahtumiin. Kest\u00e4\u00e4 yleis\u00f6massat ja kevyen kuljetuksen. Valikoima ulottuu k\u00e4velyteist\u00e4 80 tonnin levyihin.","breadcrumb":{"@id":"https:\/\/multiarena.no\/telt-og-eventgulv\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/multiarena.no\/telt-og-eventgulv\/"]}]},{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/multiarena.no\/telt-og-eventgulv\/#primaryimage","url":"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square.webp","contentUrl":"https:\/\/multiarena.no\/wp-content\/uploads\/2019\/01\/EventDeck-square.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/multiarena.no\/telt-og-eventgulv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/multiarena.no\/"},{"@type":"ListItem","position":2,"name":"Telt- og eventgulv","item":"http:\/\/multiarena.no\/en\/category\/telt-og-eventgulv\/"},{"@type":"ListItem","position":3,"name":"Telt- og Eventgulv"}]},{"@type":"WebSite","@id":"https:\/\/multiarena.no\/#website","url":"https:\/\/multiarena.no\/","name":"Multiarena AS","description":"Mobile gulv for enhver anledning!","publisher":{"@id":"https:\/\/multiarena.no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/multiarena.no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/multiarena.no\/#organization","name":"Multiarena AS","url":"https:\/\/multiarena.no\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/multiarena.no\/#\/schema\/logo\/image\/","url":"https:\/\/multiarena.no\/wp-content\/uploads\/2018\/12\/Multiarena-logo_medium.png","contentUrl":"https:\/\/multiarena.no\/wp-content\/uploads\/2018\/12\/Multiarena-logo_medium.png","width":604,"height":120,"caption":"Multiarena AS"},"image":{"@id":"https:\/\/multiarena.no\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/multiarenaas"]}]}},"_links":{"self":[{"href":"https:\/\/multiarena.no\/fi\/wp-json\/wp\/v2\/pages\/278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/multiarena.no\/fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/multiarena.no\/fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/multiarena.no\/fi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/multiarena.no\/fi\/wp-json\/wp\/v2\/comments?post=278"}],"version-history":[{"count":5,"href":"https:\/\/multiarena.no\/fi\/wp-json\/wp\/v2\/pages\/278\/revisions"}],"predecessor-version":[{"id":8518,"href":"https:\/\/multiarena.no\/fi\/wp-json\/wp\/v2\/pages\/278\/revisions\/8518"}],"wp:attachment":[{"href":"https:\/\/multiarena.no\/fi\/wp-json\/wp\/v2\/media?parent=278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/multiarena.no\/fi\/wp-json\/wp\/v2\/categories?post=278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/multiarena.no\/fi\/wp-json\/wp\/v2\/tags?post=278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}